{"id":8844,"date":"2017-10-23T15:07:02","date_gmt":"2017-10-23T14:07:02","guid":{"rendered":"http:\/\/blog.frankfurt-school.de\/?p=8844"},"modified":"2021-02-15T21:06:48","modified_gmt":"2021-02-15T20:06:48","slug":"netzwerk-aufbauen","status":"publish","type":"post","link":"https:\/\/blog.frankfurt-school.de\/de\/netzwerk-aufbauen\/","title":{"rendered":"Ein Kongress ist (auch) f\u00fcr&#8217;s Netzwerk da"},"content":{"rendered":"<p>Josh T., ein externer Trainer der Frankfurt School, plant eine gro\u00dfe Kampagne f\u00fcr die Weiterentwicklung seines Azubicamps. Er m\u00f6chte vor allem Sch\u00fcler ansprechen, die auf Ausbildungsplatzsuche sind oder einfach noch nicht wissen, was sie nach der Schule machen m\u00f6chten. In diesem Jahr hat er erstmalig ein Azubicamp f\u00fcr eine Woche in der Eifel durchgef\u00fchrt und viele angehende Fachkr\u00e4fte daf\u00fcr gewinnen k\u00f6nnen. Dennoch kann er auf kein funktionierendes Netzwerk mit den \u201erichtigen Personen\u201c zur\u00fcckgreifen, um seine Arbeit deutschlandweit fortzusetzen.<\/p>\n<p>Besser, als ein externes Netzwerk, wie zum Beispiel das des Azubimanagement, zu nutzen, was auch zu Irritationen bei der Zielgruppe f\u00fchren kann, ist es, ein eigenes Netzwerk aufzubauen. Und es w\u00e4re auch nur im ersten Schritt geholfen, Informationen \u00fcber unser Netzwerk zu streuen. Deshalb habe ich Josh andere Informationen gegeben\u2013 Tipps und Tricks, wie er sich genau das aufbauen kann.<\/p>\n<p>Zun\u00e4chst hat fast jeder ein Netzwerk aus Freunden, Bekannten und beruflichen Kontakten, die wiederum ein Netzwerk aus Freunden, Bekannten und beruflichen Kontakten haben. Zu oft nutzen wir das nur nicht. Im schlimmsten Fall nutzen wir Bekannte im Bedarfsfall und vergessen dabei das Wichtigste: die Pflege der Bekanntschaft.<\/p>\n<p><strong>Tipp Nr. 1: Bekanntenkreis anschauen.<br \/>\n<\/strong>Wo arbeiten die Menschen aus Ihrem\/Deinem Netzwerk, welche Ausbildungen und Berufsgruppen sind vertreten, welche Weiterentwicklungen haben sie gemacht? Denn man sollte das Potenzial eines bestehenden Kontaktes nie untersch\u00e4tzen.<\/p>\n<h2><strong>Netzwerk \u00fcber Veranstaltungen<\/strong><\/h2>\n<p>Um neue Kontakte zu schlie\u00dfen, bieten sich eine Messe oder ein Kongress an. Aber wie geht man am besten vor? Vielen Menschen \u2013 wie Josh \u2013 f\u00e4llt es eher schwer, fremde Menschen anzusprechen. Das stimmt, die Barriere ist gro\u00df und wie kommt man ins Gespr\u00e4ch? Oftmals sind ja auch zwei Personen aus einem Unternehmen unterwegs. Sich \u201eeinzuklinken\u201c wirkt f\u00fcr viele oft nicht echt. Das echte Interesse an Themen und Menschen ist in diesem Fall Voraussetzung. Man muss ein ernsthaftes Interesse am Gegen\u00fcber haben, um ins Gespr\u00e4ch zu kommen. Und dies ist leichter als gedacht. Jeder Mensch hat Interessantes zu erz\u00e4hlen \u2013 und gerade auf Veranstaltungen wie einer Messe und\/oder einem Kongress ist die Wahrscheinlichkeit sehr gro\u00df, Menschen mit gleichem oder zumindest \u00e4hnlichen beruflichen Hintergrund zu treffen. Das Gespr\u00e4chsthema ist also fast vorgegeben. Mit einem ehrlichen Interesse am Gegen\u00fcber gelingt es auch, die richtigen Fragen zu stellen.<\/p>\n<p><strong>Tipp Nr. 2: Einstiegss\u00e4tze f\u00fcr ein Gespr\u00e4ch<\/strong><br \/>\nWenn sich zum Beispiel die Situation ergibt, sich f\u00fcr einen Vortrag neben einen Unbekannten zu setzen, empfehlen sich diese S\u00e4tze:<\/p>\n<ul>\n<li>\u201eIst der Platz neben Ihnen frei?<\/li>\n<li>\u201eIch bin schon gespannt auf den Vortrag. Kennen Sie den Redner?\u201c (nach der Platznahme)<\/li>\n<\/ul>\n<p>Der neue Gespr\u00e4chspartner muss dabei die M\u00f6glichkeit haben, auf die Fragen einzugehen. Wirkt die Antwort kurz angebunden und gibt es kein merkbares Gegeninteresse am Gespr\u00e4chsaufbau, sollte man es dabei belassen: Vielleicht ergibt sich ja w\u00e4hrend oder nach dem Vortrag die Gelegenheit, noch einmal ins Gespr\u00e4ch zu kommen.<\/p>\n<p>Oder es ergibt sich die Situation, sich zum Essen an einen Stehtisch zu stellen, wo bereits Personen stehen, die er nicht kennt.<\/p>\n<ul>\n<li>\u201eGuten Tag, darf ich mich zu Ihnen stellen?<\/li>\n<li>\u201eDas sieht ja alles sehr lecker aus. Schmeckt es Ihnen?\u201c (in die Runde)<\/li>\n<\/ul>\n<p>Hier geht es im ersten Schritt nicht um fachliche Themen, sondern darum, sich kennenzulernen und locker in ein Gespr\u00e4ch zu starten.<\/p>\n<p><strong>Tipp Nr. 3: Akzeptieren Sie Ihr Gegen\u00fcber<\/strong><\/p>\n<p>Bei der Kontaktaufnahme ist eine Regel ganz wichtig: kein Gespr\u00e4ch aufzwingen, sondern die Reaktionen des Gegen\u00fcbers akzeptieren. Es kommt auf das gute Gesp\u00fcr an, anderen Personen \u00a0Raum zur Reaktion zu geben oder die richtige Situation zu erkennen, um auf sich aufmerksam zu machen und Fragen der anderen zu beantworten.<\/p>\n<p>Genauso ist es m\u00f6glich, zun\u00e4chst von sich zu erz\u00e4hlen, sich vorzustellen und die Visitenkarte proaktiv auszugeben. Auf einem Kongress bieten sich eine Vielzahl solcher Gespr\u00e4chsans\u00e4tze und damit auch die M\u00f6glichkeit, sich gut zu mit bisher fremden Personen auszutauschen. Ein interessantes Netzwerk f\u00fcr Josh kann entstehen, wenn er die Kontakte individuell pflegt und versprochene Informationen zuverl\u00e4ssig liefert. Denn auch Josh ist Teil des Netzwerkes der Anderen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Josh T., ein externer Trainer der Frankfurt School, plant eine gro\u00dfe Kampagne f\u00fcr die Weiterentwicklung seines Azubicamps. Er m\u00f6chte vor allem Sch\u00fcler ansprechen, die auf Ausbildungsplatzsuche sind oder einfach noch nicht wissen, was sie nach der Schule machen m\u00f6chten. In diesem Jahr hat er erstmalig ein Azubicamp f\u00fcr eine Woche in der Eifel durchgef\u00fchrt und [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":15694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[51],"tags":[115,344,1749,904,905,906,907,908,362,100,232,909,123],"class_list":["post-8844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-executive-education","tag-ausbildung","tag-azubimanagement","tag-fstraining","tag-kongress","tag-kongresse","tag-messe","tag-messen","tag-network","tag-networking","tag-newsletter-de","tag-social-media","tag-veranstaltungen","tag-weiterbildung"],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/posts\/8844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/comments?post=8844"}],"version-history":[{"count":3,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/posts\/8844\/revisions"}],"predecessor-version":[{"id":18444,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/posts\/8844\/revisions\/18444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/media\/15694"}],"wp:attachment":[{"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/media?parent=8844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/categories?post=8844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.frankfurt-school.de\/de\/wp-json\/wp\/v2\/tags?post=8844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}